{"id":3,"date":"2024-02-23T19:25:03","date_gmt":"2024-02-23T19:25:03","guid":{"rendered":"https:\/\/galsarsoluciones.com\/?page_id=3"},"modified":"2026-05-01T17:35:25","modified_gmt":"2026-05-01T17:35:25","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/galsarsoluciones.com\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\n<section class=\"legal-page\">\n  <div class=\"legal-page__inner\">\n\n    <header class=\"legal-page__header\">\n      <span class=\"legal-page__eyebrow\">Informaci\u00f3n legal<\/span>\n      <h1>Pol\u00edtica de Privacidad<\/h1>\n      <p>\n        En esta p\u00e1gina encontrar\u00e1s informaci\u00f3n sobre el tratamiento y protecci\u00f3n de datos personales en el sitio web de Galsar Soluciones.\n      <\/p>\n    <\/header>\n\n    <div class=\"legal-page__content\">\n\n      <h2>I. Pol\u00edtica de privacidad y protecci\u00f3n de datos<\/h2>\n\n      <p>\n        Respetando lo establecido en la legislaci\u00f3n vigente, Galsar Soluciones, en adelante tambi\u00e9n Sitio Web, se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos.\n      <\/p>\n\n      <h2>Leyes que incorpora esta pol\u00edtica de privacidad<\/h2>\n\n      <p>\n        Esta pol\u00edtica de privacidad est\u00e1 adaptada a la normativa espa\u00f1ola y europea vigente en materia de protecci\u00f3n de datos personales en internet. En concreto, la misma respeta las siguientes normas:\n      <\/p>\n\n      <ul>\n        <li>El Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/li>\n        <li>La Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPD-GDD).<\/li>\n        <li>El Real Decreto 1720\/2007, de 21 de diciembre, por el que se aprueba el Reglamento de desarrollo de la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal (RDLOPD).<\/li>\n        <li>La Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE).<\/li>\n      <\/ul>\n\n      <h2>Identidad del responsable del tratamiento de los datos personales<\/h2>\n\n      <p>\n        <strong>Direcci\u00f3n:<\/strong> PRIMADO REIG N\u00ba129, 46020 Val\u00e8ncia (Valencia)\n      <\/p>\n\n      <p>\n        <strong>Email de contacto:<\/strong> <a href=\"mailto:admon@galsarsoluciones.com\">admon@galsarsoluciones.com<\/a>\n      <\/p>\n\n      <h2>Registro de Datos de Car\u00e1cter Personal<\/h2>\n\n      <p>\n        En cumplimiento de lo establecido en el RGPD y la LOPD-GDD, le informamos que los datos personales recabados por Galsar Soluciones, mediante los formularios extendidos en sus p\u00e1ginas, quedar\u00e1n incorporados y ser\u00e1n tratados en nuestro fichero con el fin de poder facilitar, agilizar y cumplir los compromisos establecidos entre Galsar Soluciones y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este rellene, o para atender una solicitud o consulta del mismo.\n      <\/p>\n\n      <p>\n        Asimismo, de conformidad con lo previsto en el RGPD y la LOPD-GDD, salvo que sea de aplicaci\u00f3n la excepci\u00f3n prevista en el art\u00edculo 30.5 del RGPD, se mantiene un registro de actividades de tratamiento que especifica, seg\u00fan sus finalidades, las actividades de tratamiento llevadas a cabo y las dem\u00e1s circunstancias establecidas en el RGPD.\n      <\/p>\n\n      <h2>Principios aplicables al tratamiento de los datos personales<\/h2>\n\n      <p>\n        El tratamiento de los datos personales del Usuario se someter\u00e1 a los siguientes principios recogidos en el art\u00edculo 5 del RGPD y en el art\u00edculo 4 y siguientes de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:\n      <\/p>\n\n      <ul>\n        <li><strong>Principio de licitud, lealtad y transparencia:<\/strong> se requerir\u00e1 en todo momento el consentimiento del Usuario previa informaci\u00f3n completamente transparente de los fines para los cuales se recogen los datos personales.<\/li>\n        <li><strong>Principio de limitaci\u00f3n de la finalidad:<\/strong> los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos.<\/li>\n        <li><strong>Principio de minimizaci\u00f3n de datos:<\/strong> los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados.<\/li>\n        <li><strong>Principio de exactitud:<\/strong> los datos personales deben ser exactos y estar siempre actualizados.<\/li>\n        <li><strong>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n:<\/strong> los datos personales solo ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n del Usuario durante el tiempo necesario para los fines de su tratamiento.<\/li>\n        <li><strong>Principio de integridad y confidencialidad:<\/strong> los datos personales ser\u00e1n tratados de manera que se garantice su seguridad y confidencialidad.<\/li>\n        <li><strong>Principio de responsabilidad proactiva:<\/strong> el Responsable del tratamiento ser\u00e1 responsable de asegurar que los principios anteriores se cumplen.<\/li>\n      <\/ul>\n\n      <h2>Categor\u00edas de datos personales<\/h2>\n\n      <p>\n        Las categor\u00edas de datos que se tratan en Galsar Soluciones son \u00fanicamente datos identificativos. En ning\u00fan caso se tratan categor\u00edas especiales de datos personales en el sentido del art\u00edculo 9 del RGPD.\n      <\/p>\n\n      <h2>Base legal para el tratamiento de los datos personales<\/h2>\n\n      <p>\n        La base legal para el tratamiento de los datos personales es el consentimiento. Galsar Soluciones se compromete a recabar el consentimiento expreso y verificable del Usuario para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos.\n      <\/p>\n\n      <p>\n        El Usuario tendr\u00e1 derecho a retirar su consentimiento en cualquier momento. Ser\u00e1 tan f\u00e1cil retirar el consentimiento como darlo. Como regla general, la retirada del consentimiento no condicionar\u00e1 el uso del Sitio Web.\n      <\/p>\n\n      <p>\n        En las ocasiones en las que el Usuario deba o pueda facilitar sus datos a trav\u00e9s de formularios para realizar consultas, solicitar informaci\u00f3n o por motivos relacionados con el contenido del Sitio Web, se le informar\u00e1 en caso de que la cumplimentaci\u00f3n de alguno de ellos sea obligatoria debido a que los mismos sean imprescindibles para el correcto desarrollo de la operaci\u00f3n realizada.\n      <\/p>\n\n      <h2>Fines del tratamiento a que se destinan los datos personales<\/h2>\n\n      <p>\n        Los datos personales son recabados y gestionados por Galsar Soluciones con la finalidad de poder facilitar, agilizar y cumplir los compromisos establecidos entre el Sitio Web y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este \u00faltimo rellene o para atender una solicitud o consulta.\n      <\/p>\n\n      <p>\n        Igualmente, los datos podr\u00e1n ser utilizados con una finalidad comercial de personalizaci\u00f3n, operativa y estad\u00edstica, y actividades propias del objeto social de Galsar Soluciones, as\u00ed como para la extracci\u00f3n, almacenamiento de datos y estudios de marketing para adecuar el contenido ofertado al Usuario, as\u00ed como mejorar la calidad, funcionamiento y navegaci\u00f3n por el Sitio Web.\n      <\/p>\n\n      <p>\n        En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del fin o fines espec\u00edficos del tratamiento a que se destinar\u00e1n los datos personales; es decir, del uso o usos que se dar\u00e1 a la informaci\u00f3n recopilada.\n      <\/p>\n\n      <h2>Per\u00edodos de retenci\u00f3n de los datos personales<\/h2>\n\n      <p>\n        Los datos personales solo ser\u00e1n retenidos durante el tiempo m\u00ednimo necesario para los fines de su tratamiento y, en todo caso, \u00fanicamente durante el siguiente plazo: 12 meses, o hasta que el Usuario solicite su supresi\u00f3n.\n      <\/p>\n\n      <p>\n        En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del plazo durante el cual se conservar\u00e1n los datos personales o, cuando eso no sea posible, los criterios utilizados para determinar este plazo.\n      <\/p>\n\n      <h2>Destinatarios de los datos personales<\/h2>\n\n      <p>\n        Los datos personales del Usuario ser\u00e1n compartidos con los siguientes destinatarios o categor\u00edas de destinatarios:\n      <\/p>\n\n      <ul>\n        <li>IONOS CLOUD SL, Avenida De La Vega 1 5. 28108, Alcobendas (Madrid)<\/li>\n      <\/ul>\n\n      <p>\n        En caso de que el Responsable del tratamiento tenga la intenci\u00f3n de transferir datos personales a un tercer pa\u00eds u organizaci\u00f3n internacional, en el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del tercer pa\u00eds u organizaci\u00f3n internacional al cual se tiene la intenci\u00f3n de transferir los datos, as\u00ed como de la existencia o ausencia de una decisi\u00f3n de adecuaci\u00f3n de la Comisi\u00f3n.\n      <\/p>\n\n      <h2>Datos personales de menores de edad<\/h2>\n\n      <p>\n        Respetando lo establecido en los art\u00edculos 8 del RGPD y 7 de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales, solo los mayores de 14 a\u00f1os podr\u00e1n otorgar su consentimiento para el tratamiento de sus datos personales de forma l\u00edcita por Galsar Soluciones.\n      <\/p>\n\n      <p>\n        Si se trata de un menor de 14 a\u00f1os, ser\u00e1 necesario el consentimiento de los padres o tutores para el tratamiento, y este solo se considerar\u00e1 l\u00edcito en la medida en la que los mismos lo hayan autorizado.\n      <\/p>\n\n      <h2>Secreto y seguridad de los datos personales<\/h2>\n\n      <p>\n        Galsar Soluciones se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos, de forma que se garantice la seguridad de los datos de car\u00e1cter personal y se evite la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.\n      <\/p>\n\n      <p>\n        El Sitio Web cuenta con un certificado SSL (Secure Socket Layer), que asegura que los datos personales se transmiten de forma segura y confidencial, al ser la transmisi\u00f3n de los datos entre el servidor y el Usuario, y en retroalimentaci\u00f3n, totalmente cifrada o encriptada.\n      <\/p>\n\n      <p>\n        Sin embargo, debido a que Galsar Soluciones no puede garantizar la inexpugnabilidad de internet ni la ausencia total de hackers u otros que accedan de modo fraudulento a los datos personales, el Responsable del tratamiento se compromete a comunicar al Usuario sin dilaci\u00f3n indebida cuando ocurra una violaci\u00f3n de la seguridad de los datos personales que sea probable que entra\u00f1e un alto riesgo para los derechos y libertades de las personas f\u00edsicas.\n      <\/p>\n\n      <p>\n        Siguiendo lo establecido en el art\u00edculo 4 del RGPD, se entiende por violaci\u00f3n de la seguridad de los datos personales toda violaci\u00f3n de la seguridad que ocasione la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.\n      <\/p>\n\n      <p>\n        Los datos personales ser\u00e1n tratados como confidenciales por el Responsable del tratamiento, quien se compromete a informar de y a garantizar por medio de una obligaci\u00f3n legal o contractual que dicha confidencialidad sea respetada por sus empleados, asociados y toda persona a la cual le haga accesible la informaci\u00f3n.\n      <\/p>\n\n      <h2>Derechos derivados del tratamiento de los datos personales<\/h2>\n\n      <p>\n        El Usuario tiene sobre Galsar Soluciones y podr\u00e1, por tanto, ejercer frente al Responsable del tratamiento los siguientes derechos reconocidos en el RGPD y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:\n      <\/p>\n\n      <ul>\n        <li><strong>Derecho de acceso:<\/strong> es el derecho del Usuario a obtener confirmaci\u00f3n de si Galsar Soluciones est\u00e1 tratando o no sus datos personales y, en caso afirmativo, obtener informaci\u00f3n sobre sus datos concretos de car\u00e1cter personal y del tratamiento realizado.<\/li>\n        <li><strong>Derecho de rectificaci\u00f3n:<\/strong> es el derecho del Usuario a que se modifiquen sus datos personales que resulten ser inexactos o incompletos.<\/li>\n        <li><strong>Derecho de supresi\u00f3n:<\/strong> tambi\u00e9n conocido como \u201cderecho al olvido\u201d, es el derecho del Usuario a obtener la supresi\u00f3n de sus datos personales cuando estos ya no sean necesarios para los fines para los cuales fueron recogidos o tratados.<\/li>\n        <li><strong>Derecho a la limitaci\u00f3n del tratamiento:<\/strong> es el derecho del Usuario a limitar el tratamiento de sus datos personales en los supuestos previstos por la normativa vigente.<\/li>\n        <li><strong>Derecho a la portabilidad de los datos:<\/strong> en caso de que el tratamiento se efect\u00fae por medios automatizados, el Usuario tendr\u00e1 derecho a recibir sus datos personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica.<\/li>\n        <li><strong>Derecho de oposici\u00f3n:<\/strong> es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de Galsar Soluciones.<\/li>\n        <li><strong>Derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en el tratamiento automatizado:<\/strong> incluida la elaboraci\u00f3n de perfiles, salvo que la legislaci\u00f3n vigente establezca lo contrario.<\/li>\n      <\/ul>\n\n      <p>\n        As\u00ed pues, el Usuario podr\u00e1 ejercitar sus derechos mediante comunicaci\u00f3n escrita dirigida al Responsable del tratamiento con la referencia \u201cRGPD-https:\/\/galsarsoluciones.com\/\u201d, especificando:\n      <\/p>\n\n      <ul>\n        <li>Nombre, apellidos del Usuario y copia del DNI.<\/li>\n        <li>En los casos en que se admita la representaci\u00f3n, ser\u00e1 tambi\u00e9n necesaria la identificaci\u00f3n de la persona que representa al Usuario, as\u00ed como el documento acreditativo de la representaci\u00f3n.<\/li>\n        <li>Petici\u00f3n con los motivos espec\u00edficos de la solicitud o informaci\u00f3n a la que se quiere acceder.<\/li>\n        <li>Domicilio a efecto de notificaciones.<\/li>\n        <li>Fecha y firma del solicitante.<\/li>\n        <li>Todo documento que acredite la petici\u00f3n que formula.<\/li>\n      <\/ul>\n\n      <p>\n        Esta solicitud y todo otro documento adjunto podr\u00e1 enviarse a la siguiente direcci\u00f3n y\/o correo electr\u00f3nico:\n      <\/p>\n\n      <p>\n        <strong>Direcci\u00f3n postal:<\/strong> PRIMADO REIG N\u00ba129, 46020 Val\u00e8ncia (Valencia)\n      <\/p>\n\n      <p>\n        <strong>Correo electr\u00f3nico:<\/strong> <a href=\"mailto:admon@galsarsoluciones.com\">admon@galsarsoluciones.com<\/a>\n      <\/p>\n\n      <h2>Enlaces a sitios web de terceros<\/h2>\n\n      <p>\n        El Sitio Web puede incluir hiperv\u00ednculos o enlaces que permiten acceder a p\u00e1ginas web de terceros distintos de Galsar Soluciones, y que por tanto no son operados por Galsar Soluciones. Los titulares de dichos sitios web dispondr\u00e1n de sus propias pol\u00edticas de protecci\u00f3n de datos, siendo ellos mismos responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad.\n      <\/p>\n\n      <h2>Reclamaciones ante la autoridad de control<\/h2>\n\n      <p>\n        En caso de que el Usuario considere que existe un problema o infracci\u00f3n de la normativa vigente en la forma en la que se est\u00e1n tratando sus datos personales, tendr\u00e1 derecho a la tutela judicial efectiva y a presentar una reclamaci\u00f3n ante una autoridad de control.\n      <\/p>\n\n      <p>\n        En el caso de Espa\u00f1a, la autoridad de control es la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos:\n        <a href=\"http:\/\/www.agpd.es\" target=\"_blank\" rel=\"noopener\">www.agpd.es<\/a>.\n      <\/p>\n\n      <h2>II. Aceptaci\u00f3n y cambios en esta pol\u00edtica de privacidad<\/h2>\n\n      <p>\n        Es necesario que el Usuario haya le\u00eddo y est\u00e9 conforme con las condiciones sobre la protecci\u00f3n de datos de car\u00e1cter personal contenidas en esta Pol\u00edtica de Privacidad, as\u00ed como que acepte el tratamiento de sus datos personales para que el Responsable del tratamiento pueda proceder al mismo en la forma, durante los plazos y para las finalidades indicadas.\n      <\/p>\n\n      <p>\n        El uso del Sitio Web implicar\u00e1 la aceptaci\u00f3n de la Pol\u00edtica de Privacidad del mismo.\n      <\/p>\n\n      <p>\n        Galsar Soluciones se reserva el derecho a modificar su Pol\u00edtica de Privacidad, de acuerdo a su propio criterio, o motivado por un cambio legislativo, jurisprudencial o doctrinal de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos.\n      <\/p>\n\n      <p>\n        Los cambios o actualizaciones de esta Pol\u00edtica de Privacidad no ser\u00e1n notificados de forma expl\u00edcita al Usuario. Se recomienda al Usuario consultar esta p\u00e1gina de forma peri\u00f3dica para estar al tanto de los \u00faltimos cambios o actualizaciones.\n      <\/p>\n\n      <p>\n        Esta Pol\u00edtica de Privacidad fue actualizada para adaptarse al Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, y a la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales.\n      <\/p>\n\n    <\/div>\n  <\/div>\n<\/section>\n\n<style>\n.legal-page {\n  padding: 90px 20px;\n  background:\n    radial-gradient(circle at 50% 10%, rgba(3, 140, 255, 0.10), transparent 28%),\n    radial-gradient(circle at 12% 22%, rgba(14, 88, 174, 0.08), transparent 24%),\n    linear-gradient(180deg, #f7fbff 0%, #ffffff 52%, #f3f8fd 100%);\n}\n\n.legal-page__inner {\n  max-width: 980px;\n  margin: 0 auto;\n}\n\n.legal-page__header {\n  margin-bottom: 44px;\n  text-align: center;\n}\n\n.legal-page__eyebrow {\n  display: inline-block;\n  margin-bottom: 14px;\n  padding: 6px 10px;\n  border-radius: 999px;\n  background: rgba(3, 140, 255, 0.08);\n  color: #038cff;\n  font-size: 0.76rem;\n  font-weight: 700;\n  letter-spacing: 0.1em;\n  text-transform: uppercase;\n}\n\n.legal-page__header h1 {\n  margin: 0;\n  color: #0e58ae;\n  font-size: clamp(2rem, 4vw, 3.4rem);\n  line-height: 1.08;\n  letter-spacing: -0.03em;\n  font-weight: 700;\n}\n\n.legal-page__header p {\n  max-width: 720px;\n  margin: 18px auto 0;\n  color: #47657f;\n  font-size: 1.08rem;\n  line-height: 1.7;\n}\n\n.legal-page__content {\n  padding: 44px;\n  border-radius: 28px;\n  background: #ffffff;\n  border: 1px solid rgba(15, 76, 129, 0.08);\n  box-shadow: 0 14px 34px rgba(15, 30, 50, 0.06);\n}\n\n.legal-page__content h2 {\n  margin: 42px 0 14px;\n  color: #0e58ae;\n  font-size: clamp(1.35rem, 2.2vw, 1.9rem);\n  line-height: 1.2;\n  letter-spacing: -0.02em;\n  font-weight: 700;\n}\n\n.legal-page__content h2:first-child {\n  margin-top: 0;\n}\n\n.legal-page__content p {\n  margin: 16px 0;\n  color: #47657f;\n  font-size: 1rem;\n  line-height: 1.75;\n}\n\n.legal-page__content ul {\n  margin: 16px 0 24px;\n  padding-left: 22px;\n}\n\n.legal-page__content li {\n  margin-bottom: 9px;\n  color: #47657f;\n  line-height: 1.65;\n}\n\n.legal-page__content strong {\n  color: #0b2a45;\n  font-weight: 700;\n}\n\n.legal-page__content a {\n  color: #0e58ae;\n  font-weight: 700;\n  text-decoration: none;\n}\n\n.legal-page__content a:hover {\n  color: #038cff;\n  text-decoration: underline;\n}\n\n@media (max-width: 700px) {\n  .legal-page {\n    padding: 70px 20px;\n  }\n\n  .legal-page__content {\n    padding: 28px 22px;\n    border-radius: 22px;\n  }\n}\n<\/style>\n\n\n<style>.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-lg, 4rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-4xl, 8rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(35% - ((var(--global-kb-gap-lg, 4rem) * 3 )\/4)))minmax(0, calc(20% - ((var(--global-kb-gap-lg, 4rem) * 3 )\/4)))minmax(0, calc(25% - ((var(--global-kb-gap-lg, 4rem) * 3 )\/4)))minmax(0, calc(20% - ((var(--global-kb-gap-lg, 4rem) * 3 )\/4)));}.kb-row-layout-id879_87b76c-31 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 767px){.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id879_87b76c-31 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id879_87b76c-31 alignnone has-theme-palette8-background-color kt-row-has-bg galsar-footer wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column879_06a2e2-9f > .kt-inside-inner-col,.kadence-column879_06a2e2-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_06a2e2-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_06a2e2-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column879_06a2e2-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column879_06a2e2-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_06a2e2-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column879_06a2e2-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column879_06a2e2-9f > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}.kadence-column879_06a2e2-9f, .kt-inside-inner-col > .kadence-column879_06a2e2-9f:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_06a2e2-9f\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-site-logo\"><a href=\"https:\/\/galsarsoluciones.com\/en\/\" class=\"custom-logo-link\" rel=\"home\"><img decoding=\"async\" width=\"245\" height=\"94\" src=\"https:\/\/galsarsoluciones.com\/wp-content\/uploads\/2026\/04\/galsar_letras-negro.webp\" class=\"custom-logo\" alt=\"Galsar Soluciones\" \/><\/a><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84, .wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84[data-kb-block=\"kb-adv-heading879_eb8ce3-84\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;color:#252525;}.wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84[data-kb-block=\"kb-adv-heading879_eb8ce3-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_eb8ce3-84[data-kb-block=\"kb-adv-heading879_eb8ce3-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading879_eb8ce3-84 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_eb8ce3-84\">Automatizaci\u00f3n industrial para empresas que no pueden permitirse fallos.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27, .wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27[data-kb-block=\"kb-adv-heading879_73ebd4-27\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;color:#252525;}.wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27[data-kb-block=\"kb-adv-heading879_73ebd4-27\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_73ebd4-27[data-kb-block=\"kb-adv-heading879_73ebd4-27\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading879_73ebd4-27 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_73ebd4-27\">Ll\u00e1manos al <a href=\"tel:+34960200321\">+34960200321<\/a><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b, .wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b[data-kb-block=\"kb-adv-heading879_b0573a-4b\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;color:#252525;}.wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b[data-kb-block=\"kb-adv-heading879_b0573a-4b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_b0573a-4b[data-kb-block=\"kb-adv-heading879_b0573a-4b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading879_b0573a-4b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_b0573a-4b\"><a href=\"mailto:comunicacion@galsarsoluciones.com\">comunicacion@galsarsoluciones.com<\/a><\/p>\n\n\n<style>.kt-svg-icons879_e8fa22-71 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons879_e8fa22-71{justify-content:flex-start;gap:var(--global-kb-gap-sm, 1rem);}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons879_e8fa22-71 alignnone\"><style>.kt-svg-item-879_3cd681-9e .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-879_3cd681-9e .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:24px;}.kt-svg-item-879_3cd681-9e:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-879_3cd681-9e\"><a href=\"https:\/\/www.linkedin.com\/company\/galsar-soluciones\/\" class=\"kt-svg-icon-link\" aria-label=\"Linkedin\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_linkedin\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Linkedin<\/title><path d=\"M16 8a6 6 0 0 1 6 6v7h-4v-7a2 2 0 0 0-2-2 2 2 0 0 0-2 2v7h-4v-7a6 6 0 0 1 6-6z\"\/><rect x=\"2\" y=\"9\" width=\"4\" height=\"12\"\/><circle cx=\"4\" cy=\"4\" r=\"2\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column879_cf4575-0b > .kt-inside-inner-col,.kadence-column879_cf4575-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_cf4575-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_cf4575-0b > .kt-inside-inner-col{flex-direction:column;}.kadence-column879_cf4575-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column879_cf4575-0b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_cf4575-0b{position:relative;}@media all and (max-width: 1024px){.kadence-column879_cf4575-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column879_cf4575-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_cf4575-0b\"><div class=\"kt-inside-inner-col\"><style>.kadence-column879_d85868-c4 > .kt-inside-inner-col{display:flex;}.kadence-column879_d85868-c4 > .kt-inside-inner-col{padding-top:0px;}.kadence-column879_d85868-c4 > .kt-inside-inner-col,.kadence-column879_d85868-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_d85868-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}.kadence-column879_d85868-c4 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column879_d85868-c4 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column879_d85868-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column879_d85868-c4{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_d85868-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_d85868-c4{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column879_d85868-c4{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column879_d85868-c4{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_d85868-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_d85868-c4 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39, .wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39[data-kb-block=\"kb-adv-heading879_2576c4-39\"]{padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;text-transform:uppercase;color:#000000;border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39[data-kb-block=\"kb-adv-heading879_2576c4-39\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39[data-kb-block=\"kb-adv-heading879_2576c4-39\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39, .wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39[data-kb-block=\"kb-adv-heading879_2576c4-39\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39, .wp-block-kadence-advancedheading.kt-adv-heading879_2576c4-39[data-kb-block=\"kb-adv-heading879_2576c4-39\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading879_2576c4-39 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_2576c4-39\"><strong>Empresa<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc .kb-svg-icon-wrap{color:var(--global-palette6, #718096);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-sm, 0.9rem);color:var(--global-palette3, #1A202C);}.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc .wp-block-kadence-listitem a{text-decoration:none;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc .wp-block-kadence-listitem a:hover{text-decoration:underline;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .wp-block-kadence-listitem a{color:var(--global-palette3, #1A202C);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_a8414c-fc ul.kt-svg-icon-list .wp-block-kadence-listitem a:hover{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items879_a8414c-fc kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-879_751710-c0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_751710-c0\"><a href=\"https:\/\/galsarsoluciones.com\/casos-de-exito\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Casos de \u00c9xito<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_d2179c-ff .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_d2179c-ff\"><a href=\"https:\/\/galsarsoluciones.com\/blog\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Blog<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_8d16be-3a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_8d16be-3a\"><a href=\"https:\/\/galsarsoluciones.com\/ingenieria-automatizacion-industrial\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Sobre Nosotros<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_6baad6-10 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_6baad6-10\"><a href=\"https:\/\/galsarsoluciones.com\/contacto\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Contacto<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column879_35670e-d9 > .kt-inside-inner-col{display:flex;}.kadence-column879_35670e-d9 > .kt-inside-inner-col{padding-top:0px;}.kadence-column879_35670e-d9 > .kt-inside-inner-col,.kadence-column879_35670e-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_35670e-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}.kadence-column879_35670e-d9 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column879_35670e-d9 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column879_35670e-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column879_35670e-d9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_35670e-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_35670e-d9{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column879_35670e-d9{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column879_35670e-d9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_35670e-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_35670e-d9 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40, .wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40[data-kb-block=\"kb-adv-heading879_a8d4a9-40\"]{padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;text-transform:uppercase;color:#000000;border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40[data-kb-block=\"kb-adv-heading879_a8d4a9-40\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40[data-kb-block=\"kb-adv-heading879_a8d4a9-40\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40, .wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40[data-kb-block=\"kb-adv-heading879_a8d4a9-40\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40, .wp-block-kadence-advancedheading.kt-adv-heading879_a8d4a9-40[data-kb-block=\"kb-adv-heading879_a8d4a9-40\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading879_a8d4a9-40 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_a8d4a9-40\"><strong>Servicios<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 .kb-svg-icon-wrap{color:var(--global-palette6, #718096);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-sm, 0.9rem);color:var(--global-palette3, #1A202C);}.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 .wp-block-kadence-listitem a{text-decoration:none;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 .wp-block-kadence-listitem a:hover{text-decoration:underline;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .wp-block-kadence-listitem a{color:var(--global-palette3, #1A202C);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_75c279-09 ul.kt-svg-icon-list .wp-block-kadence-listitem a:hover{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items879_75c279-09 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-879_31d5c3-1d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_31d5c3-1d\"><a href=\"https:\/\/galsarsoluciones.com\/programacion-de-plc\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Programaci\u00f3n de PLC<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_ddc524-a0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_ddc524-a0\"><a href=\"https:\/\/galsarsoluciones.com\/scada-industrial-dashboards-produccion\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Scada y Visualizaci\u00f3n<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_9694b4-d0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_9694b4-d0\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Visi\u00f3n Artificial<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_9d318b-ce .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_9d318b-ce\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Integraci\u00f3n de Sistemas<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_dbf5f3-ba .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_dbf5f3-ba\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Desarrollo de Software Industrial<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column879_519bf6-36 > .kt-inside-inner-col,.kadence-column879_519bf6-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_519bf6-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_519bf6-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column879_519bf6-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column879_519bf6-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_519bf6-36{position:relative;}@media all and (max-width: 1024px){.kadence-column879_519bf6-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column879_519bf6-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_519bf6-36\"><div class=\"kt-inside-inner-col\"><style>.kadence-column879_bffb0d-0c > .kt-inside-inner-col{display:flex;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col{padding-top:0px;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col,.kadence-column879_bffb0d-0c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column879_bffb0d-0c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column879_bffb0d-0c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column879_bffb0d-0c{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column879_bffb0d-0c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column879_bffb0d-0c > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column879_bffb0d-0c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35, .wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35[data-kb-block=\"kb-adv-heading879_be193a-35\"]{padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;text-transform:uppercase;color:#000000;border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35[data-kb-block=\"kb-adv-heading879_be193a-35\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35[data-kb-block=\"kb-adv-heading879_be193a-35\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35, .wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35[data-kb-block=\"kb-adv-heading879_be193a-35\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35, .wp-block-kadence-advancedheading.kt-adv-heading879_be193a-35[data-kb-block=\"kb-adv-heading879_be193a-35\"]{border-top:0px solid var(--global-palette6, #718096);border-right:0px solid var(--global-palette6, #718096);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading879_be193a-35 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading879_be193a-35\"><strong>Legal<\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 .kb-svg-icon-wrap{color:var(--global-palette6, #718096);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-sm, 0.9rem);color:var(--global-palette3, #1A202C);}.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 .wp-block-kadence-listitem a{text-decoration:none;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 .wp-block-kadence-listitem a:hover{text-decoration:underline;}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .wp-block-kadence-listitem a{color:var(--global-palette3, #1A202C);}.wp-block-kadence-iconlist.kt-svg-icon-list-items879_1589c6-10 ul.kt-svg-icon-list .wp-block-kadence-listitem a:hover{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items879_1589c6-10 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-879_d21c70-0e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_d21c70-0e\"><a href=\"https:\/\/galsarsoluciones.com\/politica-de-cookies\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pol\u00edtica de Cookies<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_df9e0f-23 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_df9e0f-23\"><a href=\"https:\/\/galsarsoluciones.com\/privacy-policy\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pol\u00edtica de Privacidad<\/span><\/a><\/li>\n\n\n<style>.kt-svg-icon-list-item-879_17a5a4-14 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-879_17a5a4-14\"><a href=\"https:\/\/galsarsoluciones.com\/aviso-legal-y-condiciones-generales-de-uso\/\" class=\"kt-svg-icon-link\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Aviso Legal<\/span><\/a><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n legal Pol\u00edtica de Privacidad En esta p\u00e1gina encontrar\u00e1s informaci\u00f3n sobre el tratamiento y protecci\u00f3n de datos personales en el sitio web de Galsar Soluciones. I. Pol\u00edtica de privacidad y protecci\u00f3n de datos Respetando lo establecido en la legislaci\u00f3n vigente, Galsar Soluciones, en adelante tambi\u00e9n Sitio Web, se compromete a adoptar las medidas t\u00e9cnicas y&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidad - Galsar Soluciones<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad - Galsar Soluciones\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n legal Pol\u00edtica de Privacidad En esta p\u00e1gina encontrar\u00e1s informaci\u00f3n sobre el tratamiento y protecci\u00f3n de datos personales en el sitio web de Galsar Soluciones. I. Pol\u00edtica de privacidad y protecci\u00f3n de datos Respetando lo establecido en la legislaci\u00f3n vigente, Galsar Soluciones, en adelante tambi\u00e9n Sitio Web, se compromete a adoptar las medidas t\u00e9cnicas y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/galsarsoluciones.com\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Galsar Soluciones\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T17:35:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/galsarsoluciones.com\\\/privacy-policy\\\/\",\"name\":\"Pol\u00edtica de Privacidad - Galsar Soluciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#website\"},\"datePublished\":\"2024-02-23T19:25:03+00:00\",\"dateModified\":\"2026-05-01T17:35:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/galsarsoluciones.com\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/galsarsoluciones.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#website\",\"url\":\"https:\\\/\\\/galsarsoluciones.com\\\/\",\"name\":\"Galsar Soluciones\",\"description\":\"Transformando la Industria: Conectividad, Innovaci&oacute;n y Eficiencia en Cada Proceso\",\"publisher\":{\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/galsarsoluciones.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#organization\",\"name\":\"Galsar Soluciones\",\"url\":\"https:\\\/\\\/galsarsoluciones.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/galsarsoluciones.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/galsar_letras-negro.webp\",\"contentUrl\":\"https:\\\/\\\/galsarsoluciones.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/galsar_letras-negro.webp\",\"width\":14858,\"height\":5758,\"caption\":\"Galsar Soluciones\"},\"image\":{\"@id\":\"https:\\\/\\\/galsarsoluciones.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad - Galsar Soluciones","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica de Privacidad - Galsar Soluciones","og_description":"Informaci\u00f3n legal Pol\u00edtica de Privacidad En esta p\u00e1gina encontrar\u00e1s informaci\u00f3n sobre el tratamiento y protecci\u00f3n de datos personales en el sitio web de Galsar Soluciones. I. Pol\u00edtica de privacidad y protecci\u00f3n de datos Respetando lo establecido en la legislaci\u00f3n vigente, Galsar Soluciones, en adelante tambi\u00e9n Sitio Web, se compromete a adoptar las medidas t\u00e9cnicas y...","og_url":"https:\/\/galsarsoluciones.com\/en\/privacy-policy\/","og_site_name":"Galsar Soluciones","article_modified_time":"2026-05-01T17:35:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/galsarsoluciones.com\/privacy-policy\/","url":"https:\/\/galsarsoluciones.com\/privacy-policy\/","name":"Pol\u00edtica de Privacidad - Galsar Soluciones","isPartOf":{"@id":"https:\/\/galsarsoluciones.com\/#website"},"datePublished":"2024-02-23T19:25:03+00:00","dateModified":"2026-05-01T17:35:25+00:00","breadcrumb":{"@id":"https:\/\/galsarsoluciones.com\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/galsarsoluciones.com\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/galsarsoluciones.com\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/galsarsoluciones.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/galsarsoluciones.com\/#website","url":"https:\/\/galsarsoluciones.com\/","name":"Galsar Soluciones","description":"Transformando la Industria: Conectividad, Innovaci&oacute;n y Eficiencia en Cada Proceso","publisher":{"@id":"https:\/\/galsarsoluciones.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/galsarsoluciones.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/galsarsoluciones.com\/#organization","name":"Galsar Soluciones","url":"https:\/\/galsarsoluciones.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/galsarsoluciones.com\/#\/schema\/logo\/image\/","url":"https:\/\/galsarsoluciones.com\/wp-content\/uploads\/2026\/04\/galsar_letras-negro.webp","contentUrl":"https:\/\/galsarsoluciones.com\/wp-content\/uploads\/2026\/04\/galsar_letras-negro.webp","width":14858,"height":5758,"caption":"Galsar Soluciones"},"image":{"@id":"https:\/\/galsarsoluciones.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":18,"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1233,"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/1233"}],"wp:attachment":[{"href":"https:\/\/galsarsoluciones.com\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}